{"id":2524,"count":1,"description":"","link":"https:\/\/carajput.com\/blog\/tag\/government-today-said-the-benefit-of-deduction-under-section-35ac\/","name":"Government today said the benefit of deduction under section 35AC","slug":"government-today-said-the-benefit-of-deduction-under-section-35ac","taxonomy":"post_tag","meta":[],"_links":{"self":[{"href":"https:\/\/carajput.com\/blog\/wp-json\/wp\/v2\/tags\/2524"}],"collection":[{"href":"https:\/\/carajput.com\/blog\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/carajput.com\/blog\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/carajput.com\/blog\/wp-json\/wp\/v2\/posts?tags=2524"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}